{"id":1313,"date":"2026-08-18T19:22:14","date_gmt":"2026-08-18T11:22:14","guid":{"rendered":"https:\/\/q8bbzjnpm5.wpdns.site\/profile\/"},"modified":"2026-08-19T18:55:43","modified_gmt":"2026-08-19T10:55:43","slug":"profile","status":"publish","type":"page","link":"https:\/\/subian-electric.com\/pt\/profile\/","title":{"rendered":"Perfil"},"content":{"rendered":"<p>{include file=comm\/cabecalho.html}<\/p>\n<p><main class=\"subian-ab subian-inner\"><br \/>\n    {include file=comm\/c_ban.html}<\/p>\n<section class=\"subian-ab-overview pt-120 pb-120\">\n<div class=\"w16 subian-ab-overview-grid\">\n<div class=\"subian-ab-overview-copy\">\n<div class=\"subian-ab-kicker f16\">Quem Somos<\/div>\n<h2 class=\"f44 lh-115\">Fabricando Equipamentos El\u00e9tricos Confi\u00e1veis para Distribui\u00e7\u00e3o de Energia Est\u00e1vel<\/h2>\n<div class=\"subian-ab-text f16 lh-17\">A Jiangsu Subian Power Equipment Co., Ltd. foi estabelecida em 2019 e opera uma base de fabrica\u00e7\u00e3o de aproximadamente 30.000 metros quadrados em Xuzhou, Prov\u00edncia de Jiangsu, China.<\/div>\n<div class=\"subian-ab-text f16 lh-17\">A Subian projeta e fabrica transformadores, subesta\u00e7\u00f5es pr\u00e9-fabricadas, subesta\u00e7\u00f5es fotovoltaicas elevadoras e equipamentos completos de alta e baixa tens\u00e3o. Esses produtos atendem redes el\u00e9tricas, projetos de energia renov\u00e1vel, edif\u00edcios comerciais, instala\u00e7\u00f5es industriais, aeroportos, t\u00faneis e outras aplica\u00e7\u00f5es de infraestrutura.<\/div>\n<ul class=\"subian-ab-tags\" aria-label=\"Capacidades principais\">\n<li class=\"f16 lh-14\">Fabrica\u00e7\u00e3o de Transformadores<\/li>\n<li class=\"f16 lh-14\">Solu\u00e7\u00f5es de Subesta\u00e7\u00e3o<\/li>\n<li class=\"f16 lh-14\">Equipamentos de Distribui\u00e7\u00e3o de Energia<\/li>\n<li class=\"f16 lh-14\">Suporte Baseado em Projetos<\/li>\n<\/ul><\/div>\n<div class=\"subian-ab-overview-media\">\n                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/company-overview.jpg\" alt=\"Vista a\u00e9rea da f\u00e1brica de Energia El\u00e9trica Subian\"><br \/>\n                <a href=\"\/pt\/vr\/\" class=\"subian-ab-vr f16\" aria-label=\"Abra o tour virtual da f\u00e1brica Subian\"><br \/>\n                    <i class=\"fa fa-play\" aria-hidden=\"true\"><\/i><br \/>\n                    <span>Tour pela F\u00e1brica VR<\/span><br \/>\n                <\/a>\n            <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-stats pt-100 pb-100\" aria-label=\"Fatos de fabrica\u00e7\u00e3o da empresa\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">For\u00e7a da Empresa<\/div>\n<div class=\"subian-ab-stats-head\">\n<h2 class=\"f44 lh-115\">Baseada em Capacidade Real de Fabrica\u00e7\u00e3o<\/h2>\n<div class=\"f18 lh-16\">Escala da f\u00e1brica, experi\u00eancia de produ\u00e7\u00e3o e suporte de engenharia para fornecimento confi\u00e1vel de equipamentos el\u00e9tricos.<\/div>\n<\/p><\/div>\n<ul class=\"subian-ab-stat-grid\">\n<li>\n                    <strong class=\"f38 lh-111\">2019<\/strong><br \/>\n                    <span class=\"f18 lh-13\">Experi\u00eancia em Fabrica\u00e7\u00e3o<\/span><\/p>\n<div class=\"f16 lh-16\">Fabricando transformadores, subesta\u00e7\u00f5es e equipamentos de distribui\u00e7\u00e3o de energia desde 2019.<\/div>\n<\/li>\n<li>\n                    <strong class=\"f38 lh-111\">000 m\u00b2<\/strong><br \/>\n                    <span class=\"f18 lh-13\">Base de fabrica\u00e7\u00e3o<\/span><\/p>\n<div class=\"f16 lh-16\">Espa\u00e7o para produ\u00e7\u00e3o, montagem, teste e entrega.<\/div>\n<\/li>\n<li>\n                    <strong class=\"f38 lh-111\">350+<\/strong><br \/>\n                    <span class=\"f18 lh-13\">Funcion\u00e1rios<\/span><\/p>\n<div class=\"f16 lh-16\">Suporte em engenharia, produ\u00e7\u00e3o, qualidade e vendas.<\/div>\n<\/li>\n<li>\n                    <strong class=\"f38 lh-111\">At\u00e9 110 kV<\/strong><br \/>\n                    <span class=\"f18 lh-13\">Capacidade de Solu\u00e7\u00e3o<\/span><\/p>\n<div class=\"f16 lh-16\">Equipamentos para aplica\u00e7\u00f5es de m\u00e9dia e alta tens\u00e3o.<\/div>\n<\/li>\n<\/ul><\/div>\n<\/section>\n<section class=\"subian-ab-factory pt-120 pb-120\" id=\"factory\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">Base de fabrica\u00e7\u00e3o<\/div>\n<div class=\"subian-ab-head\">\n<h2 class=\"f44 lh-115\">Base de Fabrica\u00e7\u00e3o &amp; Ambiente da F\u00e1brica<\/h2>\n<div class=\"f18 lh-16\">Um ambiente de produ\u00e7\u00e3o limpo e organizado que apoia a fabrica\u00e7\u00e3o de transformadores e equipamentos el\u00e9tricos.<\/div>\n<\/p><\/div>\n<div class=\"subian-ab-factory-grid\">\n<div class=\"subian-ab-factory-item subian-ab-factory-main\">\n<div class=\"rect-80\">\n                        <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/factory-main.webp\" class=\"_full\" alt=\"Oficina principal de produ\u00e7\u00e3o de transformadores na Subian\">\n                    <\/div>\n<div class=\"subian-ab-factory-info\">\n                        <strong class=\"f18 lh-13\">Oficina Principal de Produ\u00e7\u00e3o<\/strong><br \/>\n                        <span class=\"f16 lh-14\">\u00c1reas de produ\u00e7\u00e3o para montagem de transformadores, manuseio de componentes e fabrica\u00e7\u00e3o de equipamentos completos.<\/span>\n                    <\/div>\n<\/p><\/div>\n<div class=\"subian-ab-factory-item\">\n<div class=\"rect-55\">\n                        <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/factory-transformers.webp\" class=\"_full\" alt=\"Transformadores imersos em \u00f3leo conclu\u00eddos na f\u00e1brica\">\n                    <\/div>\n<div class=\"subian-ab-factory-info\">\n                        <strong class=\"f18 lh-13\">\u00c1rea de Produto Acabado<\/strong><br \/>\n                        <span class=\"f16 lh-14\">Transformadores conclu\u00eddos s\u00e3o preparados para inspe\u00e7\u00e3o, embalagem e entrega.<\/span>\n                    <\/div>\n<\/p><\/div>\n<div class=\"subian-ab-factory-item\">\n<div class=\"rect-55\">\n                        <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/factory-assembly.webp\" class=\"_full\" alt=\"\u00c1rea de montagem e inspe\u00e7\u00e3o de transformadores\">\n                    <\/div>\n<div class=\"subian-ab-factory-info\">\n                        <strong class=\"f18 lh-13\">\u00c1rea de Testes<\/strong><br \/>\n                        <span class=\"f16 lh-14\">Equipamentos de inspe\u00e7\u00e3o suportam a verifica\u00e7\u00e3o do produto antes da entrega.<\/span>\n                    <\/div>\n<\/p><\/div>\n<div class=\"subian-ab-factory-item\">\n<div class=\"rect-40\">\n                        <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/factory-drytype.webp\" class=\"_full\" alt=\"Transformadores de tipo seco organizados na oficina\">\n                    <\/div>\n<div class=\"subian-ab-factory-info\">\n                        <strong class=\"f18 lh-13\">\u00c1rea de Equipamentos El\u00e9tricos<\/strong><br \/>\n                        <span class=\"f16 lh-14\">Espa\u00e7o de produ\u00e7\u00e3o para transformadores de tipo seco e equipamentos de distribui\u00e7\u00e3o relacionados.<\/span>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-process pt-120 pb-120\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">Processo de Produ\u00e7\u00e3o<\/div>\n<div class=\"subian-ab-head\">\n<h2 class=\"f44 lh-115\">Procedimentos Controlados Desde a Prepara\u00e7\u00e3o at\u00e9 a Entrega<\/h2>\n<div class=\"f18 lh-16\">Desde a prepara\u00e7\u00e3o da produ\u00e7\u00e3o at\u00e9 a montagem, inspe\u00e7\u00e3o e entrega, a Subian segue procedimentos de fabrica\u00e7\u00e3o controlados.<\/div>\n<\/p><\/div>\n<ol class=\"subian-ab-process-list\">\n<li><span>01<\/span><strong class=\"f16 lh-14\">Prepara\u00e7\u00e3o de Materiais<\/strong><\/li>\n<li><span>02<\/span><strong class=\"f16 lh-14\">Processamento de Enrolamento e N\u00facleo<\/strong><\/li>\n<li><span>03<\/span><strong class=\"f16 lh-14\">Montagem<\/strong><\/li>\n<li><span>04<\/span><strong class=\"f16 lh-14\">Integra\u00e7\u00e3o de Equipamentos El\u00e9tricos<\/strong><\/li>\n<li><span>05<\/span><strong class=\"f16 lh-14\">Inspe\u00e7\u00e3o e Teste<\/strong><\/li>\n<li><span>06<\/span><strong class=\"f16 lh-14\">Embalagem e Entrega<\/strong><\/li>\n<\/ol>\n<div class=\"subian-ab-process-wrap\">\n<div class=\"swiper subian-ab-process-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-material.webp\" alt=\"\u00c1rea de prepara\u00e7\u00e3o de materiais para fabrica\u00e7\u00e3o de transformadores\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Prepara\u00e7\u00e3o de materiais e organiza\u00e7\u00e3o de componentes<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-winding.webp\" alt=\"Equipamento de produ\u00e7\u00e3o de enrolamento de transformadores\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Enrolamento controlado e processamento de bobinas<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-drying.webp\" alt=\"Equipamento de secagem a v\u00e1cuo para pe\u00e7as de transformadores\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Equipamentos de secagem a v\u00e1cuo e tratamento<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-assembly.webp\" alt=\"Processo de montagem de componentes de transformadores\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Montagem de componentes no ch\u00e3o de produ\u00e7\u00e3o<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-testing.webp\" alt=\"Equipamento de teste e inspe\u00e7\u00e3o de transformadores\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Centro de inspe\u00e7\u00e3o e verifica\u00e7\u00e3o de testes<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"subian-ab-process-card\">\n                                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/process-final.webp\" alt=\"Montagem de transformador de tipo seco conclu\u00edda\"><\/p>\n<div class=\"subian-ab-process-cap f16 lh-14\">Montagem final antes da prepara\u00e7\u00e3o para entrega<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                <button class=\"subian-ab-arrow subian-ab-process-prev\" type=\"button\" aria-label=\"Imagem da produ\u00e7\u00e3o anterior\"><i class=\"fa fa-angle-left\" aria-hidden=\"true\"><\/i><\/button><br \/>\n                <button class=\"subian-ab-arrow subian-ab-process-next\" type=\"button\" aria-label=\"Pr\u00f3xima imagem da produ\u00e7\u00e3o\"><i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/button>\n            <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-quality pt-120 pb-120\">\n<div class=\"w16 subian-ab-quality-grid\">\n<div class=\"subian-ab-quality-media\">\n                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/quality-center.webp\" alt=\"Centro de testes de transformadores Subian\">\n            <\/div>\n<div class=\"subian-ab-quality-copy\">\n<div class=\"subian-ab-kicker subian-ab-kicker-light f16\">Controle de Qualidade<\/div>\n<h2 class=\"f44 lh-115\">Fabrica\u00e7\u00e3o &amp; Controle de Qualidade<\/h2>\n<div class=\"subian-ab-quality-intro f16 lh-17\">Procedimentos de produ\u00e7\u00e3o e inspe\u00e7\u00e3o controlados suportam opera\u00e7\u00e3o confi\u00e1vel e entrega de projetos. Documentos do produto, registros de inspe\u00e7\u00e3o e materiais de qualifica\u00e7\u00e3o podem ser fornecidos de acordo com os requisitos do projeto.<\/div>\n<ul>\n<li>\n                        <i class=\"fa fa-check\" aria-hidden=\"true\"><\/i><\/p>\n<div><strong class=\"f16 lh-13\">Fabrica\u00e7\u00e3o Controlada<\/strong><span class=\"f16 lh-15\">A produ\u00e7\u00e3o e montagem seguem procedimentos definidos para apoiar a qualidade consistente do produto.<\/span><\/div>\n<\/li>\n<li>\n                        <i class=\"fa fa-check\" aria-hidden=\"true\"><\/i><\/p>\n<div><strong class=\"f16 lh-13\">Inspe\u00e7\u00e3o Rotineira<\/strong><span class=\"f16 lh-15\">Transformadores e equipamentos el\u00e9tricos s\u00e3o verificados durante a fabrica\u00e7\u00e3o e antes do envio.<\/span><\/div>\n<\/li>\n<li>\n                        <i class=\"fa fa-check\" aria-hidden=\"true\"><\/i><\/p>\n<div><strong class=\"f16 lh-13\">Documenta\u00e7\u00e3o T\u00e9cnica<\/strong><span class=\"f16 lh-15\">Documentos do produto e registros de inspe\u00e7\u00e3o s\u00e3o preparados de acordo com os requisitos do projeto.<\/span><\/div>\n<\/li>\n<li>\n                        <i class=\"fa fa-check\" aria-hidden=\"true\"><\/i><\/p>\n<div><strong class=\"f16 lh-13\">Coordena\u00e7\u00e3o de Entrega<\/strong><span class=\"f16 lh-15\">Embalagem, envio e comunica\u00e7\u00e3o do projeto s\u00e3o coordenados com o cliente.<\/span><\/div>\n<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-custom pt-120 pb-120\">\n<div class=\"w16 subian-ab-custom-grid\">\n<div class=\"subian-ab-custom-copy\">\n<div class=\"subian-ab-kicker f16\">Solu\u00e7\u00f5es Personalizadas<\/div>\n<h2 class=\"f44 lh-115\">Solu\u00e7\u00f5es Personalizadas de Equipamentos de Energia<\/h2>\n<div class=\"subian-ab-custom-text f16 lh-17\">A Subian apoia transformadores, subesta\u00e7\u00f5es e equipamentos el\u00e9tricos personalizados de acordo com n\u00edvel de tens\u00e3o, capacidade, ambiente de aplica\u00e7\u00e3o, condi\u00e7\u00f5es de instala\u00e7\u00e3o e requisitos do projeto.<\/div>\n<ul>\n<li class=\"f16 lh-15\">Revis\u00e3o de requisitos t\u00e9cnicos<\/li>\n<li class=\"f16 lh-15\">Configura\u00e7\u00e3o de produto personalizada<\/li>\n<li class=\"f16 lh-15\">Coopera\u00e7\u00e3o flex\u00edvel de OEM e ODM<\/li>\n<li class=\"f16 lh-15\">Coordena\u00e7\u00e3o de produ\u00e7\u00e3o e entrega<\/li>\n<\/ul>\n<p>                <a href=\"\/pt\/oem-odm\/\" class=\"subian-ab-btn subian-ab-btn-main f16\">Explorar OEM \/ ODM<\/a>\n            <\/div>\n<div class=\"subian-ab-custom-media\">\n                <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/custom-winding.webp\" alt=\"T\u00e9cnico operando equipamento de enrolamento de transformadores\">\n            <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-certs pt-120 pb-120\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">Documenta\u00e7\u00e3o de Qualidade<\/div>\n<div class=\"subian-ab-head\">\n<h2 class=\"f44 lh-115\">Certificados &amp; Documenta\u00e7\u00e3o de Qualidade<\/h2>\n<div class=\"f18 lh-16\">Materiais de qualifica\u00e7\u00e3o, relat\u00f3rios de teste de produto e registros de inspe\u00e7\u00e3o podem ser fornecidos de acordo com os requisitos do projeto.<\/div>\n<\/p><\/div>\n<div class=\"subian-ab-cert-wrap\">\n<div class=\"swiper subian-ab-cert-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-10kv-dry-type.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"10 kV Dry-Type Transformer Certificate\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-10kv-dry-type.webp\" alt=\"Certificado TUV para transformadores de tipo seco Subian 10 kV\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Certificado de Transformador Tipo Seco de 10 kV<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-35kv-cb.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"35 kV Transformer CB Certificate\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-35kv-cb.webp\" alt=\"Certificado de teste CB para transformadores de pot\u00eancia Subian 35 kV\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Certificado de Transformador CB de 35 kV<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-35kv-ce.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"35 kV Transformer CE Verification\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-35kv-ce.webp\" alt=\"Verifica\u00e7\u00e3o de teste CE para transformadores de pot\u00eancia Subian 35 kV\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Verifica\u00e7\u00e3o CE de Transformador de 35 kV<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-ce.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"Transformer CE Certificate\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-ce.webp\" alt=\"Certificado CE para a linha de transformadores Subian\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Certificado CE de Transformador<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-cn26i11c.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"Dry-Type Transformer Test Verification\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-cn26i11c.webp\" alt=\"Verifica\u00e7\u00e3o de teste TUV para transformadores de tipo seco Subian\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Verifica\u00e7\u00e3o de Teste de Transformador Tipo Seco<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-iso-14001.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"ISO 14001 Environmental Management\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-iso-14001.webp\" alt=\"Certificado do sistema de gest\u00e3o ambiental ISO 14001\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">ISO 14001 Gest\u00e3o Ambiental<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-iso-45001.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"ISO 45001 Health &amp; Safety\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-iso-45001.webp\" alt=\"Certificado de sa\u00fade e seguran\u00e7a ocupacional ISO 45001\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">ISO 45001 Sa\u00fade &amp; Seguran\u00e7a<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-iso-9001.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"ISO 9001 Quality Management\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-iso-9001.webp\" alt=\"Certificado do sistema de gest\u00e3o da qualidade ISO 9001\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">ISO 9001 Gest\u00e3o da Qualidade<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-ssz22-63000-110-nx1.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"110 kV Transformer Type Test Report\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-ssz22-63000-110-nx1.webp\" alt=\"Relat\u00f3rio de teste de tipo para transformador de pot\u00eancia Subian SSZ22 110 kV\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Relat\u00f3rio de Teste de Tipo de Transformador de 110 kV<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<div class=\"swiper-slide\">\n                            <a href=\"\/pt\/{pboot:sitetplpath}\/images\/about\/certificate-ul.webp\/\" class=\"subian-ab-cert glightbox3\" data-gallery=\"subian-about-certificates\" data-title=\"UL Certificate of Compliance\"><br \/>\n                                <span><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/certificate-ul.webp\" alt=\"Certificado de conformidade UL para transformadores preenchidos com l\u00edquido Subian\"><\/span><br \/>\n                                <strong class=\"f18 lh-13\">Certificado de Conformidade UL<\/strong><br \/>\n                            <\/a>\n                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                <button class=\"subian-ab-arrow subian-ab-cert-prev\" type=\"button\" aria-label=\"Certificado anterior\"><i class=\"fa fa-angle-left\" aria-hidden=\"true\"><\/i><\/button><br \/>\n                <button class=\"subian-ab-arrow subian-ab-cert-next\" type=\"button\" aria-label=\"Pr\u00f3ximo certificado\"><i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/button>\n            <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-global pt-120 pb-120\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">Comunica\u00e7\u00e3o com o Cliente<\/div>\n<div class=\"subian-ab-head\">\n<h2 class=\"f44 lh-115\">Exposi\u00e7\u00f5es &amp; Comunica\u00e7\u00e3o com o Cliente<\/h2>\n<div class=\"f18 lh-16\">A Subian se comunica com clientes e parceiros de projeto atrav\u00e9s de exposi\u00e7\u00f5es do setor, visitas \u00e0 f\u00e1brica e discuss\u00f5es de projeto.<\/div>\n<\/p><\/div>\n<div class=\"subian-ab-global-wrap\">\n<div class=\"swiper subian-ab-global-swiper\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<article class=\"subian-ab-global-card\">\n<div class=\"subian-ab-global-media\">\n<div class=\"rect-60 subian-ab-global-ratio\"><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/exhibition-booth.webp\" alt=\"Estande da exposi\u00e7\u00e3o da Subian Electric Power\" class=\"_full\"><\/div>\n<\/div>\n<div class=\"subian-ab-global-copy\">\n                                    <span class=\"f16 lh-13\">Exposi\u00e7\u00e3o do Setor<\/span><\/p>\n<h3 class=\"f30 lh-12\">Estande de Exposi\u00e7\u00e3o do Setor<\/h3>\n<div class=\"f16 lh-17\">A Subian apresenta solu\u00e7\u00f5es de transformadores e equipamentos de energia em exposi\u00e7\u00f5es profissionais do setor.<\/div>\n<\/p><\/div>\n<\/article><\/div>\n<div class=\"swiper-slide\">\n<article class=\"subian-ab-global-card\">\n<div class=\"subian-ab-global-media\">\n<div class=\"rect-60 subian-ab-global-ratio\"><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/exhibition-talk.webp\" alt=\"Equipe Subian conversando com um cliente em uma exposi\u00e7\u00e3o\" class=\"_full\"><\/div>\n<\/div>\n<div class=\"subian-ab-global-copy\">\n                                    <span class=\"f16 lh-13\">Discuss\u00e3o de Projeto<\/span><\/p>\n<h3 class=\"f30 lh-12\">Discuss\u00e3o de Produto com o Cliente<\/h3>\n<div class=\"f16 lh-17\">A comunica\u00e7\u00e3o face a face ajuda a esclarecer requisitos de produto, condi\u00e7\u00f5es do projeto e detalhes t\u00e9cnicos.<\/div>\n<\/p><\/div>\n<\/article><\/div>\n<div class=\"swiper-slide\">\n<article class=\"subian-ab-global-card\">\n<div class=\"subian-ab-global-media\">\n<div class=\"rect-60 subian-ab-global-ratio\"><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/exhibition-partners.webp\" alt=\"Visitantes internacionais no estande da exposi\u00e7\u00e3o Subian\" class=\"_full\"><\/div>\n<\/div>\n<div class=\"subian-ab-global-copy\">\n                                    <span class=\"f16 lh-13\">Parceiros de Projeto<\/span><\/p>\n<h3 class=\"f30 lh-12\">Reuni\u00e3o de Parceiros<\/h3>\n<div class=\"f16 lh-17\">Fornecemos aos parceiros de projeto informa\u00e7\u00f5es sobre produtos, detalhes de fabrica\u00e7\u00e3o e suporte a cota\u00e7\u00f5es.<\/div>\n<\/p><\/div>\n<\/article><\/div>\n<div class=\"swiper-slide\">\n<article class=\"subian-ab-global-card\">\n<div class=\"subian-ab-global-media\">\n<div class=\"rect-60 subian-ab-global-ratio\"><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/visit-factory.webp\" alt=\"Clientes internacionais visitando o equipamento de produ\u00e7\u00e3o Subian\" class=\"_full\"><\/div>\n<\/div>\n<div class=\"subian-ab-global-copy\">\n                                    <span class=\"f16 lh-13\">Visita \u00e0 F\u00e1brica<\/span><\/p>\n<h3 class=\"f30 lh-12\">Comunica\u00e7\u00e3o de Visita \u00e0 F\u00e1brica<\/h3>\n<div class=\"f16 lh-17\">Os clientes podem visitar a f\u00e1brica para entender o ambiente de produ\u00e7\u00e3o e o processo de fabrica\u00e7\u00e3o.<\/div>\n<\/p><\/div>\n<\/article><\/div>\n<div class=\"swiper-slide\">\n<article class=\"subian-ab-global-card\">\n<div class=\"subian-ab-global-media\">\n<div class=\"rect-60 subian-ab-global-ratio\"><img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/visit-meeting.webp\" alt=\"Reuni\u00e3o de clientes na Subian Electric Power\" class=\"_full\"><\/div>\n<\/div>\n<div class=\"subian-ab-global-copy\">\n                                    <span class=\"f16 lh-13\">Reuni\u00e3o T\u00e9cnica<\/span><\/p>\n<h3 class=\"f30 lh-12\">Discuss\u00e3o T\u00e9cnica<\/h3>\n<div class=\"f16 lh-17\">Nossas equipes de engenharia e vendas revisam n\u00edvel de tens\u00e3o, capacidade, configura\u00e7\u00e3o do produto e requisitos de aplica\u00e7\u00e3o.<\/div>\n<\/p><\/div>\n<\/article><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                <button class=\"subian-ab-arrow subian-ab-global-prev\" type=\"button\" aria-label=\"Imagem da exposi\u00e7\u00e3o anterior\"><i class=\"fa fa-angle-left\" aria-hidden=\"true\"><\/i><\/button><br \/>\n                <button class=\"subian-ab-arrow subian-ab-global-next\" type=\"button\" aria-label=\"Pr\u00f3xima imagem da exposi\u00e7\u00e3o\"><i class=\"fa fa-angle-right\" aria-hidden=\"true\"><\/i><\/button><\/p>\n<div class=\"subian-ab-global-pagination\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-delivery pt-120 pb-120\">\n<div class=\"w16\">\n<div class=\"subian-ab-kicker f16\">Embalagem &amp; Carregamento<\/div>\n<div class=\"subian-ab-head\">\n<h2 class=\"f44 lh-115\">Embalagem Confi\u00e1vel e Prepara\u00e7\u00e3o para Envio<\/h2>\n<div class=\"f18 lh-16\">Transformadores, subesta\u00e7\u00f5es e equipamentos el\u00e9tricos acabados s\u00e3o embalados e carregados de acordo com o tipo de produto, condi\u00e7\u00f5es de transporte e requisitos do projeto.<\/div>\n<\/p><\/div>\n<div class=\"subian-ab-delivery-grid\">\n<div class=\"subian-ab-delivery-item\">\n                    <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/delivery-loading.webp\" alt=\"Caixas de madeira e equipamentos de pot\u00eancia sendo carregados para entrega\"><\/p>\n<div class=\"subian-ab-delivery-info\"><strong class=\"f18 lh-13\">Embalagem Protegida<\/strong><span class=\"f16 lh-15\">Equipamentos e acess\u00f3rios seguros para transporte.<\/span><\/div>\n<\/p><\/div>\n<div class=\"subian-ab-delivery-item\">\n                    <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/delivery-fleet.webp\" alt=\"Ve\u00edculos de entrega Subian do lado de fora da f\u00e1brica\"><\/p>\n<div class=\"subian-ab-delivery-info\"><strong class=\"f18 lh-13\">Despacho Coordenado<\/strong><span class=\"f16 lh-15\">Cronogramas de entrega alinhados com os planos do projeto.<\/span><\/div>\n<\/p><\/div>\n<div class=\"subian-ab-delivery-item\">\n                    <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/about\/delivery-packed.webp\" alt=\"Equipamento el\u00e9trico embalado pronto para envio\"><\/p>\n<div class=\"subian-ab-delivery-info\"><strong class=\"f18 lh-13\">Pronto para Envio<\/strong><span class=\"f16 lh-15\">Verifica\u00e7\u00f5es finais conclu\u00eddas antes do equipamento sair.<\/span><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"subian-ab-cta pt-100 pb-100\">\n        <img decoding=\"async\" src=\"{pboot:sitetplpath}\/images\/subian-substation-line.svg\" class=\"subian-ab-cta-line\" alt=\"\"><\/p>\n<div class=\"w16 subian-ab-cta-in\">\n<div>\n<div class=\"subian-ab-kicker subian-ab-kicker-light f16\">Consulta de Projeto<\/div>\n<h2 class=\"f44 lh-115\">Precisa de Mais Informa\u00e7\u00f5es Sobre a Subian?<\/h2>\n<div class=\"subian-ab-cta-text f16 lh-16\">Informe-nos seu interesse no produto, n\u00edvel de tens\u00e3o, capacidade e requisitos de aplica\u00e7\u00e3o. Nossa equipe fornecer\u00e1 informa\u00e7\u00f5es sobre o produto, suporte de cota\u00e7\u00e3o e comunica\u00e7\u00e3o do projeto.<\/div>\n<\/p><\/div>\n<div class=\"subian-ab-actions\">\n                <a href=\"\/pt\/contact-us\/\" class=\"subian-ab-btn subian-ab-btn-white f16\">Contate Nossa Equipe<\/a><br \/>\n                <a href=\"\/pt\/oem-odm\/\" class=\"subian-ab-btn subian-ab-btn-ghost f16\">Suporte OEM \/ ODM<\/a>\n            <\/div>\n<\/p><\/div>\n<\/section>\n<p><\/main><\/p>\n<p>{include file=comm\/rodape.html}<\/p>","protected":false},"excerpt":{"rendered":"<p>{include file=comm\/head.html} {include file=comm\/c_ban.html} Who We Are Manufacturing Reliable Power Equipment for Stable Power Distribution Jiangsu Subian Power Equipment Co., Ltd. was established in 2019 and operates a manufacturing base of approximately 30,000 square meters in Xuzhou, Jiangsu Province, China. Subian designs and manufactures transformers, prefabricated substations, photovoltaic step-up substations and complete high and low [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":1629,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1313","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/pages\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":2,"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/pages\/1313\/revisions"}],"predecessor-version":[{"id":1773,"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/pages\/1313\/revisions\/1773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/media\/1629"}],"wp:attachment":[{"href":"https:\/\/subian-electric.com\/pt\/wp-json\/wp\/v2\/media?parent=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}